{"id":4978,"date":"2026-04-27T10:55:13","date_gmt":"2026-04-27T08:55:13","guid":{"rendered":"https:\/\/ilingua.uvigo.gal\/?post_type=blog&#038;p=4978"},"modified":"2026-04-27T10:59:05","modified_gmt":"2026-04-27T08:59:05","slug":"reunions-coas-candidaturas","status":"publish","type":"blog","link":"https:\/\/ilingua.uvigo.gal\/es\/blog\/reunions-coas-candidaturas\/","title":{"rendered":"Reuniones con las candidaturas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En la semana del 6 de abril, previa al inicio de la campa\u00f1a electoral, el iLingua invit\u00f3 a las tres personas candidatas a rector\/a de la UVigo, Carmen Garc\u00eda, Jacobo Porteiro y Bel\u00e9n Rubio, a mantener charlas virtuales, en las que el director del iLingua les transmiti\u00f3\u00a0las necesidades del Instituto y les pregunt\u00f3 sobre su posicionamiento cara a este. En concreto, hablaron del lugar que deben ocupar los Institutos en la estructura de unidades de investigaci\u00f3n en la UVigo, el financiamiento y personal de estes y el reconocimiento de la labor de gesti\u00f3n en el c\u00f3mputo de la dedicaci\u00f3n del personal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1005\" src=\"https:\/\/ilingua.uvigo.gal\/wp-content\/uploads\/Diseno-sin-titulo-1024x1005.jpg\" alt=\"\" class=\"wp-image-4979\" srcset=\"https:\/\/ilingua.uvigo.gal\/wp-content\/uploads\/Diseno-sin-titulo-1024x1005.jpg 1024w, https:\/\/ilingua.uvigo.gal\/wp-content\/uploads\/Diseno-sin-titulo-300x294.jpg 300w, https:\/\/ilingua.uvigo.gal\/wp-content\/uploads\/Diseno-sin-titulo-768x754.jpg 768w, https:\/\/ilingua.uvigo.gal\/wp-content\/uploads\/Diseno-sin-titulo-1536x1508.jpg 1536w, https:\/\/ilingua.uvigo.gal\/wp-content\/uploads\/Diseno-sin-titulo.jpg 1630w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En la semana del 6 de abril, previa al inicio de la campa\u00f1a electoral, el iLingua invit\u00f3 a las tres personas candidatas a rector\/a de la UVigo, Carmen Garc\u00eda, Jacobo [&hellip;]<\/p>\n","protected":false},"featured_media":4979,"template":"","class_list":["post-4978","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ilingua.uvigo.gal\/es\/wp-json\/wp\/v2\/blog\/4978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ilingua.uvigo.gal\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/ilingua.uvigo.gal\/es\/wp-json\/wp\/v2\/types\/blog"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ilingua.uvigo.gal\/es\/wp-json\/wp\/v2\/media\/4979"}],"wp:attachment":[{"href":"https:\/\/ilingua.uvigo.gal\/es\/wp-json\/wp\/v2\/media?parent=4978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}